{"id":24611,"date":"2026-05-13T08:54:49","date_gmt":"2026-05-13T11:54:49","guid":{"rendered":"https:\/\/www.fcejs.unsl.edu.ar\/?p=24611"},"modified":"2026-05-13T08:54:49","modified_gmt":"2026-05-13T11:54:49","slug":"el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior","status":"publish","type":"post","link":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/","title":{"rendered":"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior"},"content":{"rendered":"<p>El Consejo Directivo de la Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales (FCEJS) aprob\u00f3 en su sesi\u00f3n del d\u00eda 6 de mayo oficialmente el Programa Puentes Acad\u00e9micos. Esta iniciativa surge con el objetivo de fortalecer la articulaci\u00f3n entre la universidad y las escuelas secundarias, promoviendo as\u00ed el acceso, la permanencia y el egreso de j\u00f3venes y adultos a la educaci\u00f3n superior p\u00fablica, libre y gratuita.<\/p>\n<p>La creaci\u00f3n del programa que estar\u00e1 a cargo de la Secretar\u00eda Acad\u00e9mica, se enmarca en una concepci\u00f3n de la Universidad P\u00fablica como motor de una sociedad m\u00e1s justa, igualitaria e inclusiva. El Programa Puentes Acad\u00e9micos busca desarrollar acciones conjuntas con las escuelas secundarias, centradas en las necesidades y proyectos de vida de los y las estudiantes, para favorecer un acceso real y efectivo al derecho a la educaci\u00f3n.<\/p>\n<p>Este programa se propone generar espacios interinstitucionales que sirvan de &#8220;andamiaje seguro&#8221; para acompa\u00f1ar a los y las estudiantes en la transici\u00f3n entre la escuela secundaria y la universidad. Se abordar\u00e1n las dificultades que se presentan en este traspaso, como las administrativas, la brecha entre conocimientos, la incertidumbre profesional, la necesidad de autonom\u00eda y la adaptaci\u00f3n a una nueva cultura institucional.<\/p>\n<p>El Programa Puentes Acad\u00e9micos tendr\u00e1 entre sus tareas el contacto con escuelas secundarias, el relevamiento de intereses formativos, la coordinaci\u00f3n de propuestas de trabajo, la promoci\u00f3n de la oferta educativa de la UNSL y la articulaci\u00f3n de acciones concretas. El equipo de trabajo estar\u00e1 conformado por docentes, estudiantes, graduados\/as y nodocentes de la FCEJS, y las actividades se desarrollar\u00e1n a lo largo del a\u00f1o acad\u00e9mico en las instalaciones de la Facultad y en los establecimientos educativos secundarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo Directivo de la Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales (FCEJS) aprob\u00f3 en su sesi\u00f3n del d\u00eda 6 de mayo oficialmente el Programa&hellip;<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-24611","post","type-post","status-publish","format-standard","hentry","category-archivadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior - Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior - Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales\" \/>\n<meta property=\"og:description\" content=\"El Consejo Directivo de la Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales (FCEJS) aprob\u00f3 en su sesi\u00f3n del d\u00eda 6 de mayo oficialmente el Programa&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/\" \/>\n<meta property=\"og:site_name\" content=\"Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FCEJS.UNSL\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:54:49+00:00\" \/>\n<meta name=\"author\" content=\"Matias Videla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FCEJSUNSL\" \/>\n<meta name=\"twitter:site\" content=\"@FCEJSUNSL\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matias Videla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/\"},\"author\":{\"name\":\"Matias Videla\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#\\\/schema\\\/person\\\/c2cc0d213e1b2c7a7770ef32f65de25b\"},\"headline\":\"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior\",\"datePublished\":\"2026-05-13T11:54:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/\"},\"wordCount\":323,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#organization\"},\"articleSection\":[\"Archivadas\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/\",\"url\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/\",\"name\":\"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior - Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#website\"},\"datePublished\":\"2026-05-13T11:54:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/index.php\\\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#website\",\"url\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/\",\"name\":\"Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#organization\",\"name\":\"Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales\",\"url\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/logo-1.jpg\",\"width\":471,\"height\":146,\"caption\":\"Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FCEJS.UNSL\\\/\",\"https:\\\/\\\/x.com\\\/FCEJSUNSL\",\"https:\\\/\\\/www.instagram.com\\\/fcejs.unsl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCH-Ut6EaN_X5ogjIQMPe46g\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fcejs.unsl.edu.ar\\\/#\\\/schema\\\/person\\\/c2cc0d213e1b2c7a7770ef32f65de25b\",\"name\":\"Matias Videla\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior - Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/","og_locale":"es_ES","og_type":"article","og_title":"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior - Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales","og_description":"El Consejo Directivo de la Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales (FCEJS) aprob\u00f3 en su sesi\u00f3n del d\u00eda 6 de mayo oficialmente el Programa&hellip;","og_url":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/","og_site_name":"Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales","article_publisher":"https:\/\/www.facebook.com\/FCEJS.UNSL\/","article_published_time":"2026-05-13T11:54:49+00:00","author":"Matias Videla","twitter_card":"summary_large_image","twitter_creator":"@FCEJSUNSL","twitter_site":"@FCEJSUNSL","twitter_misc":{"Escrito por":"Matias Videla","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/#article","isPartOf":{"@id":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/"},"author":{"name":"Matias Videla","@id":"https:\/\/www.fcejs.unsl.edu.ar\/#\/schema\/person\/c2cc0d213e1b2c7a7770ef32f65de25b"},"headline":"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior","datePublished":"2026-05-13T11:54:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/"},"wordCount":323,"publisher":{"@id":"https:\/\/www.fcejs.unsl.edu.ar\/#organization"},"articleSection":["Archivadas"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/","url":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/","name":"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior - Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales","isPartOf":{"@id":"https:\/\/www.fcejs.unsl.edu.ar\/#website"},"datePublished":"2026-05-13T11:54:49+00:00","breadcrumb":{"@id":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/el-consejo-directivo-de-fcejs-aprobo-la-creacion-del-programa-puentes-academicos-para-facilitar-el-acceso-a-la-educacion-superior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.fcejs.unsl.edu.ar\/"},{"@type":"ListItem","position":2,"name":"El Consejo Directivo de FCEJS aprob\u00f3 la creaci\u00f3n del Programa Puentes Acad\u00e9micos para facilitar el acceso a la educaci\u00f3n superior"}]},{"@type":"WebSite","@id":"https:\/\/www.fcejs.unsl.edu.ar\/#website","url":"https:\/\/www.fcejs.unsl.edu.ar\/","name":"Facultad de Ciencias Econ\u00f3micas, Jur\u00ed\u00addicas y Sociales","description":"","publisher":{"@id":"https:\/\/www.fcejs.unsl.edu.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fcejs.unsl.edu.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/www.fcejs.unsl.edu.ar\/#organization","name":"Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales","url":"https:\/\/www.fcejs.unsl.edu.ar\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/www.fcejs.unsl.edu.ar\/#\/schema\/logo\/image\/","url":"https:\/\/www.fcejs.unsl.edu.ar\/wp-content\/uploads\/2021\/03\/logo-1.jpg","contentUrl":"https:\/\/www.fcejs.unsl.edu.ar\/wp-content\/uploads\/2021\/03\/logo-1.jpg","width":471,"height":146,"caption":"Facultad de Ciencias Econ\u00f3micas, Jur\u00eddicas y Sociales"},"image":{"@id":"https:\/\/www.fcejs.unsl.edu.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FCEJS.UNSL\/","https:\/\/x.com\/FCEJSUNSL","https:\/\/www.instagram.com\/fcejs.unsl\/","https:\/\/www.youtube.com\/channel\/UCH-Ut6EaN_X5ogjIQMPe46g\/"]},{"@type":"Person","@id":"https:\/\/www.fcejs.unsl.edu.ar\/#\/schema\/person\/c2cc0d213e1b2c7a7770ef32f65de25b","name":"Matias Videla"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/24611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=24611"}],"version-history":[{"count":2,"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/24611\/revisions"}],"predecessor-version":[{"id":24617,"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/24611\/revisions\/24617"}],"wp:attachment":[{"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=24611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=24611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fcejs.unsl.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=24611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}